{"id":13674,"date":"2023-09-19T14:44:03","date_gmt":"2023-09-19T13:44:03","guid":{"rendered":"https:\/\/dev.ignfi.fr\/news\/"},"modified":"2026-01-21T11:40:08","modified_gmt":"2026-01-21T10:40:08","slug":"news","status":"publish","type":"page","link":"https:\/\/ignfi.fr\/en\/news\/","title":{"rendered":"News"},"content":{"rendered":"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; left_padding_phone=&#8221;0&#8243; constrain_group_6=&#8221;yes&#8221; right_padding_phone=&#8221;0&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; top_margin_tablet=&#8221;-10%&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;0px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221; column_padding_type=&#8221;default&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bottom_padding=&#8221;15&#8243; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][nectar_post_grid post_type=&#8221;post&#8221; blog_category=&#8221;all&#8221; order=&#8221;DESC&#8221; orderby=&#8221;date&#8221; pagination=&#8221;none&#8221; columns=&#8221;1&#8243; columns_tablet=&#8221;default&#8221; columns_phone=&#8221;default&#8221; grid_item_spacing=&#8221;15px&#8221; grid_item_height=&#8221;60vh&#8221; image_size=&#8221;full&#8221; image_loading=&#8221;lazy-load&#8221; animation=&#8221;none&#8221; animation_stagger=&#8221;90&#8243; animation_easing=&#8221;default&#8221; parallax_scrolling=&#8221;yes&#8221; heading_tag=&#8221;default&#8221; font_size_max=&#8221;48px&#8221; display_categories=&#8221;yes&#8221; category_functionality=&#8221;default&#8221; category_position=&#8221;default&#8221; category_style=&#8221;button&#8221; category_display=&#8221;parent_only&#8221; additional_meta_size=&#8221;small&#8221; grid_style=&#8221;content_overlaid&#8221; text_content_layout=&#8221;all_bottom_left_shadow&#8221; color_overlay=&#8221;#000000&#8243; color_overlay_opacity=&#8221;0.3&#8243; color_overlay_hover_opacity=&#8221;0.4&#8243; text_color=&#8221;light&#8221; text_color_hover=&#8221;light&#8221; text_opacity=&#8221;1&#8243; text_hover_opacity=&#8221;1&#8243; hover_effect=&#8221;zoom&#8221; border_radius=&#8221;10px&#8221; content_overlaid_padding_desktop=&#8221;50px&#8221; content_overlaid_padding_tablet=&#8221;35px&#8221; posts_per_page=&#8221;1&#8243; display_type=&#8221;grid&#8221; custom_font_size=&#8221;2.4vw&#8221; font_size_tablet=&#8221;26px&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column top_padding_desktop=&#8221;2%&#8221; bottom_padding_desktop=&#8221;2%&#8221; left_padding_desktop=&#8221;5%&#8221; right_padding_desktop=&#8221;5%&#8221; left_padding_tablet=&#8221;0&#8243; right_padding_tablet=&#8221;0&#8243; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; gradient_type=&#8221;default&#8221;][nectar_post_grid post_type=&#8221;post&#8221; blog_category=&#8221;all&#8221; order=&#8221;DESC&#8221; orderby=&#8221;date&#8221; pagination=&#8221;none&#8221; ignore_sticky_posts=&#8221;yes&#8221; columns=&#8221;1&#8243; columns_tablet=&#8221;default&#8221; columns_phone=&#8221;default&#8221; grid_item_spacing=&#8221;10px&#8221; image_size=&#8221;portfolio-thumb_large&#8221; aspect_ratio_image_size=&#8221;yes&#8221; custom_image_aspect_ratio=&#8221;3-2&#8243; content_next_to_image_image_width=&#8221;33.3%&#8221; content_next_to_image_image_gap=&#8221;10%&#8221; content_next_to_image_image_position=&#8221;right&#8221; image_loading=&#8221;lazy-load&#8221; animation=&#8221;none&#8221; animation_stagger=&#8221;90&#8243; animation_easing=&#8221;default&#8221; heading_tag=&#8221;h3&#8243; font_size_min=&#8221;16px&#8221; font_size_max=&#8221;24px&#8221; display_categories=&#8221;yes&#8221; category_functionality=&#8221;static&#8221; category_position=&#8221;default&#8221; category_style=&#8221;underline&#8221; category_display=&#8221;parent_only&#8221; additional_meta_size=&#8221;small&#8221; grid_style=&#8221;content_next_to_image&#8221; text_color=&#8221;dark&#8221; content_next_to_image_vertical_align=&#8221;middle&#8221; hover_effect=&#8221;animated_underline&#8221; border_radius=&#8221;10px&#8221; content_next_to_image_divider=&#8221;yes&#8221; content_next_to_image_divider_color=&#8221;#e5e5e5&#8243; posts_per_page=&#8221;2&#8243; display_type=&#8221;grid&#8221; custom_font_size=&#8221;1.4vw&#8221; font_line_height=&#8221;1.3&#8243; post_offset=&#8221;1&#8243;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;custom&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; bottom_padding=&#8221;5%&#8221; top_padding_tablet=&#8221;15&#8243; bottom_padding_phone=&#8221;15%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;0px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221; column_padding_type=&#8221;advanced&#8221;][nectar_post_grid post_type=&#8221;post&#8221; blog_category=&#8221;all&#8221; order=&#8221;DESC&#8221; orderby=&#8221;date&#8221; pagination=&#8221;load-more&#8221; button_color=&#8221;accent-color&#8221; columns=&#8221;4&#8243; columns_tablet=&#8221;default&#8221; columns_phone=&#8221;default&#8221; grid_item_spacing=&#8221;15px&#8221; grid_item_height=&#8221;60vh&#8221; 4_col_masonry_layout=&#8221;default&#8221; image_size=&#8221;full&#8221; aspect_ratio_image_size=&#8221;yes&#8221; custom_image_aspect_ratio=&#8221;4-3&#8243; image_loading=&#8221;lazy-load&#8221; animation=&#8221;none&#8221; animation_stagger=&#8221;90&#8243; animation_easing=&#8221;default&#8221; parallax_scrolling=&#8221;yes&#8221; heading_tag=&#8221;default&#8221; font_size_min=&#8221;16px&#8221; font_size_max=&#8221;24px&#8221; display_categories=&#8221;yes&#8221; category_functionality=&#8221;default&#8221; category_position=&#8221;default&#8221; category_style=&#8221;button&#8221; category_display=&#8221;parent_only&#8221; additional_meta_size=&#8221;small&#8221; grid_style=&#8221;content_under_image&#8221; content_under_image_text_align=&#8221;left&#8221; text_color=&#8221;dark&#8221; hover_effect=&#8221;zoom&#8221; border_radius=&#8221;10px&#8221; custom_font_size=&#8221;1.2vw&#8221; posts_per_page=&#8221;8&#8243; display_type=&#8221;grid&#8221; post_offset=&#8221;3&#8243;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; zindex=&#8221;auto&#8221; overflow=&#8221;hidden&#8221; disable_element=&#8221;yes&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; enable_shape_divider=&#8221;true&#8221; shape_divider_color=&#8221;#000000&#8243; shape_divider_position=&#8221;bottom&#8221; shape_divider_height=&#8221;1px&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;straight_section&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;0px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221; column_padding_type=&#8221;default&#8221;][nectar_scrolling_text scroll_direction=&#8221;rtl&#8221; scroll_speed=&#8221;slow&#8221; text_color=&#8221;#0a0a0a&#8221; move_on_scroll_animation=&#8221;yes&#8221; style=&#8221;text_outline&#8221; outline_thickness=&#8221;ultra-thin&#8221; outline_applies_to=&#8221;text_only&#8221; text_repeat_number=&#8221;3&#8243; text_repeat_divider=&#8221;custom&#8221; text_repeat_divider_scale=&#8221;half&#8221; text_repeat_divider_custom_spin_animation=&#8221;yes&#8221; overflow=&#8221;visible&#8221; background_image_animation=&#8221;None&#8221; custom_font_size=&#8221;10vw&#8221; custom_font_size_mobile=&#8221;13vw&#8221; text_repeat_divider_custom=&#8221;\u2731&#8221;]\n<h2>HOT POSTS<\/h2>\n[\/nectar_scrolling_text][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;absolute&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; top_position_desktop=&#8221;0&#8243; left_position_desktop=&#8221;0&#8243; max_width_desktop=&#8221;100%&#8221; zindex=&#8221;500&#8243; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_scrolling_text scroll_direction=&#8221;rtl&#8221; scroll_speed=&#8221;slow&#8221; text_color=&#8221;#0a0a0a&#8221; move_on_scroll_animation=&#8221;yes&#8221; style=&#8221;text_outline&#8221; outline_thickness=&#8221;ultra-thin&#8221; outline_applies_to=&#8221;both&#8221; text_repeat_number=&#8221;3&#8243; text_repeat_divider=&#8221;custom&#8221; text_repeat_divider_scale=&#8221;half&#8221; text_repeat_divider_custom_spin_animation=&#8221;yes&#8221; overflow=&#8221;visible&#8221; background_image_animation=&#8221;None&#8221; custom_font_size=&#8221;10vw&#8221; custom_font_size_mobile=&#8221;13vw&#8221; text_repeat_divider_custom=&#8221;\u2731&#8221;]\n<h2><em>HOT POSTS<\/em><\/h2>\n[\/nectar_scrolling_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; left_padding_phone=&#8221;0&#8243; constrain_group_6=&#8221;yes&#8221; right_padding_phone=&#8221;0&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221;&#8230;<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-13674","page","type-page","status-publish"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>News - IGNFI<\/title>\n<meta name=\"description\" content=\"News | Explore the latest articles covering IGN FI&#039;s highlights, commitments, impactful projects, and press mentions.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ignfi.fr\/en\/news\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"News - IGNFI\" \/>\n<meta property=\"og:description\" content=\"News | Explore the latest articles covering IGN FI&#039;s highlights, commitments, impactful projects, and press mentions.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ignfi.fr\/en\/news\/\" \/>\n<meta property=\"og:site_name\" content=\"IGNFI\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-21T10:40:08+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ignfi.fr\\\/en\\\/news\\\/\",\"url\":\"https:\\\/\\\/ignfi.fr\\\/en\\\/news\\\/\",\"name\":\"News - IGNFI\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ignfi.fr\\\/en\\\/#website\"},\"datePublished\":\"2023-09-19T13:44:03+00:00\",\"dateModified\":\"2026-01-21T10:40:08+00:00\",\"description\":\"News | Explore the latest articles covering IGN FI's highlights, commitments, impactful projects, and press mentions.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ignfi.fr\\\/en\\\/news\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ignfi.fr\\\/en\\\/news\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ignfi.fr\\\/en\\\/news\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/ignfi.fr\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ignfi.fr\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ignfi.fr\\\/en\\\/\",\"name\":\"IGNFI\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ignfi.fr\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"News - IGNFI","description":"News | Explore the latest articles covering IGN FI's highlights, commitments, impactful projects, and press mentions.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ignfi.fr\/en\/news\/","og_locale":"en_US","og_type":"article","og_title":"News - IGNFI","og_description":"News | Explore the latest articles covering IGN FI's highlights, commitments, impactful projects, and press mentions.","og_url":"https:\/\/ignfi.fr\/en\/news\/","og_site_name":"IGNFI","article_modified_time":"2026-01-21T10:40:08+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ignfi.fr\/en\/news\/","url":"https:\/\/ignfi.fr\/en\/news\/","name":"News - IGNFI","isPartOf":{"@id":"https:\/\/ignfi.fr\/en\/#website"},"datePublished":"2023-09-19T13:44:03+00:00","dateModified":"2026-01-21T10:40:08+00:00","description":"News | Explore the latest articles covering IGN FI's highlights, commitments, impactful projects, and press mentions.","breadcrumb":{"@id":"https:\/\/ignfi.fr\/en\/news\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ignfi.fr\/en\/news\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ignfi.fr\/en\/news\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/ignfi.fr\/en\/"},{"@type":"ListItem","position":2,"name":"News"}]},{"@type":"WebSite","@id":"https:\/\/ignfi.fr\/en\/#website","url":"https:\/\/ignfi.fr\/en\/","name":"IGNFI","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ignfi.fr\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/ignfi.fr\/en\/wp-json\/wp\/v2\/pages\/13674","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ignfi.fr\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ignfi.fr\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ignfi.fr\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/ignfi.fr\/en\/wp-json\/wp\/v2\/comments?post=13674"}],"version-history":[{"count":6,"href":"https:\/\/ignfi.fr\/en\/wp-json\/wp\/v2\/pages\/13674\/revisions"}],"predecessor-version":[{"id":14826,"href":"https:\/\/ignfi.fr\/en\/wp-json\/wp\/v2\/pages\/13674\/revisions\/14826"}],"wp:attachment":[{"href":"https:\/\/ignfi.fr\/en\/wp-json\/wp\/v2\/media?parent=13674"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}